{"id":241619,"date":"2009-06-01T00:00:00","date_gmt":"2009-05-31T23:00:00","guid":{"rendered":"http:\/\/vo.hollands-spoor.com\/schrijvers\/j-m-a-biesheuvel\/"},"modified":"2025-12-02T13:27:39","modified_gmt":"2025-12-02T12:27:39","slug":"j-m-a-biesheuvel","status":"publish","type":"oorschot_writer","link":"https:\/\/www.vanoorschot.nl\/en\/writers\/j-m-a-biesheuvel\/","title":{"rendered":"J.M.A. Biesheuvel"},"content":{"rendered":"<p>J.M.A. Biesheuvel (Schiedam, 1939 &#8211; Leiden, 2020) debuteerde in 1972 met de verhalenbundel <em>In de bovenkooi<\/em>. Daarna volgden talloze bundels, altijd bestaande uit korte verhalen en novellen, waaronder <em>De weg naar het licht<\/em>, <em>De angstkunstenaar<\/em>, <em>De verpletterende werkelijkheid<\/em>, <em>Reis door mijn kamer<\/em> en kleinere uitgaven als <em>Motje tegen gloeiend lampepeertje<\/em> en <em>Oude geschiedenis van Pa<\/em>. In 2008 verscheen zijn <em>Verzameld werk<\/em>, drie delen in een linnen cassette, bestaande uit al het gebundelde werk aangevuld met het een en ander dat alleen bibliofiel was verschenen.<br \/>\nBiesheuvels verhalen zijn veelal autobiografisch van inslag. Hij schreef zowel over zijn ervaringen als matroos op koopvaardijschepen, over zijn depressies en zijn verblijf in wat hij <em>unverfroren<\/em> het gekkenhuis noemt, over zijn vrouw Eva, over zijn huis en werkkamer, over zijn jeugd. Daarnaast schreef hij verhalen waarin fantasie de vrije loop krijgt.<\/p>\n<p>Op 15 december 2006 werd aan Biesheuvel de P.C. Hooftprijs voor zijn verhalend proza toegekend. \u2018Biesheuvels associatieve verteltechniek geeft zijn proza een weldadig effect en irrationaliteit en onlogica, waardoor het fantastisch element te meer een kans krijgt\u2019, aldus de jury onder leiding van Maarten Asscher. De jury prijst verder Biesheuvels \u2018verbeeldingskracht, absurdistische humor en stilistische rijkdom\u2019.<br \/>\nIn januari 2007 verscheen een herziene en uitgebreide herdruk van <em>Zeeverhalen<\/em>, waaraan een cd werd toegevoegd waarop Biesheuvel zijn meest recente verhalen voorleest.<\/p>\n<p>\u2018Veel van wat Maarten Biesheuvel schrijft is waar gebeurd. Maar sommige dingen die hij schrijft zijn gelogen. Mijn moeilijkheid is dat ik nooit helemaal zeker weet of wat hij schrijft nu waar gebeurd is of niet.\u2019<br \/>\n\u2013 Karel van het Reve<\/p>\n<p>Voor veel meer informatie zie: <a href=\"http:\/\/www.jmabiesheuvel.nl\" target=\"_blank\" rel=\"noopener noreferrer\">www.jmabiesheuvel.nl<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>J.M.A. Biesheuvel (Schiedam, 1939 &#8211; Leiden, 2020) debuteerde in 1972 met de verhalenbundel In de bovenkooi. Daarna volgden talloze bundels, altijd bestaande uit korte verhalen en novellen, waaronder De weg naar het licht, De angstkunstenaar, De verpletterende werkelijkheid, Reis door mijn kamer en kleinere uitgaven als Motje tegen gloeiend lampepeertje en Oude geschiedenis van Pa&#8230;. <a class=\"more-link\" href=\"https:\/\/www.vanoorschot.nl\/en\/writers\/j-m-a-biesheuvel\/\">Lees verder <span class=\"read-more-arrow\"><\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":241620,"menu_order":158,"comment_status":"closed","ping_status":"open","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-241619","oorschot_writer","type-oorschot_writer","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>J.M.A. Biesheuvel &#183; Uitgeverij Van Oorschot<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vanoorschot.nl\/en\/writers\/j-m-a-biesheuvel\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"J.M.A. Biesheuvel &#183; Uitgeverij Van Oorschot\" \/>\n<meta property=\"og:description\" content=\"J.M.A. Biesheuvel (Schiedam, 1939 &#8211; Leiden, 2020) debuteerde in 1972 met de verhalenbundel In de bovenkooi. Daarna volgden talloze bundels, altijd bestaande uit korte verhalen en novellen, waaronder De weg naar het licht, De angstkunstenaar, De verpletterende werkelijkheid, Reis door mijn kamer en kleinere uitgaven als Motje tegen gloeiend lampepeertje en Oude geschiedenis van Pa.... Lees verder\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vanoorschot.nl\/en\/writers\/j-m-a-biesheuvel\/\" \/>\n<meta property=\"og:site_name\" content=\"Uitgeverij Van Oorschot\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-02T12:27:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vanoorschot.nl\/wp-content\/uploads\/2019\/06\/Biesheuvel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vanoorschot.nl\/en\/writers\/j-m-a-biesheuvel\/\",\"url\":\"https:\/\/www.vanoorschot.nl\/en\/writers\/j-m-a-biesheuvel\/\",\"name\":\"J.M.A. Biesheuvel &#183; Uitgeverij Van Oorschot\",\"isPartOf\":{\"@id\":\"https:\/\/www.vanoorschot.nl\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.vanoorschot.nl\/en\/writers\/j-m-a-biesheuvel\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.vanoorschot.nl\/en\/writers\/j-m-a-biesheuvel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.vanoorschot.nl\/wp-content\/uploads\/2019\/06\/Biesheuvel.jpg\",\"datePublished\":\"2009-05-31T23:00:00+00:00\",\"dateModified\":\"2025-12-02T12:27:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.vanoorschot.nl\/en\/writers\/j-m-a-biesheuvel\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vanoorschot.nl\/en\/writers\/j-m-a-biesheuvel\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.vanoorschot.nl\/en\/writers\/j-m-a-biesheuvel\/#primaryimage\",\"url\":\"https:\/\/www.vanoorschot.nl\/wp-content\/uploads\/2019\/06\/Biesheuvel.jpg\",\"contentUrl\":\"https:\/\/www.vanoorschot.nl\/wp-content\/uploads\/2019\/06\/Biesheuvel.jpg\",\"width\":250,\"height\":375},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.vanoorschot.nl\/en\/writers\/j-m-a-biesheuvel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.vanoorschot.nl\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Van Oorschot writers\",\"item\":\"https:\/\/www.vanoorschot.nl\/en\/writers\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"J.M.A. Biesheuvel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vanoorschot.nl\/en\/#website\",\"url\":\"https:\/\/www.vanoorschot.nl\/en\/\",\"name\":\"Uitgeverij Van Oorschot\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vanoorschot.nl\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"J.M.A. Biesheuvel &#183; Uitgeverij Van Oorschot","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vanoorschot.nl\/en\/writers\/j-m-a-biesheuvel\/","og_locale":"en_US","og_type":"article","og_title":"J.M.A. Biesheuvel &#183; Uitgeverij Van Oorschot","og_description":"J.M.A. Biesheuvel (Schiedam, 1939 &#8211; Leiden, 2020) debuteerde in 1972 met de verhalenbundel In de bovenkooi. Daarna volgden talloze bundels, altijd bestaande uit korte verhalen en novellen, waaronder De weg naar het licht, De angstkunstenaar, De verpletterende werkelijkheid, Reis door mijn kamer en kleinere uitgaven als Motje tegen gloeiend lampepeertje en Oude geschiedenis van Pa.... Lees verder","og_url":"https:\/\/www.vanoorschot.nl\/en\/writers\/j-m-a-biesheuvel\/","og_site_name":"Uitgeverij Van Oorschot","article_modified_time":"2025-12-02T12:27:39+00:00","og_image":[{"width":250,"height":375,"url":"https:\/\/www.vanoorschot.nl\/wp-content\/uploads\/2019\/06\/Biesheuvel.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vanoorschot.nl\/en\/writers\/j-m-a-biesheuvel\/","url":"https:\/\/www.vanoorschot.nl\/en\/writers\/j-m-a-biesheuvel\/","name":"J.M.A. Biesheuvel &#183; Uitgeverij Van Oorschot","isPartOf":{"@id":"https:\/\/www.vanoorschot.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vanoorschot.nl\/en\/writers\/j-m-a-biesheuvel\/#primaryimage"},"image":{"@id":"https:\/\/www.vanoorschot.nl\/en\/writers\/j-m-a-biesheuvel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vanoorschot.nl\/wp-content\/uploads\/2019\/06\/Biesheuvel.jpg","datePublished":"2009-05-31T23:00:00+00:00","dateModified":"2025-12-02T12:27:39+00:00","breadcrumb":{"@id":"https:\/\/www.vanoorschot.nl\/en\/writers\/j-m-a-biesheuvel\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vanoorschot.nl\/en\/writers\/j-m-a-biesheuvel\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.vanoorschot.nl\/en\/writers\/j-m-a-biesheuvel\/#primaryimage","url":"https:\/\/www.vanoorschot.nl\/wp-content\/uploads\/2019\/06\/Biesheuvel.jpg","contentUrl":"https:\/\/www.vanoorschot.nl\/wp-content\/uploads\/2019\/06\/Biesheuvel.jpg","width":250,"height":375},{"@type":"BreadcrumbList","@id":"https:\/\/www.vanoorschot.nl\/en\/writers\/j-m-a-biesheuvel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vanoorschot.nl\/en\/"},{"@type":"ListItem","position":2,"name":"Van Oorschot writers","item":"https:\/\/www.vanoorschot.nl\/en\/writers\/"},{"@type":"ListItem","position":3,"name":"J.M.A. Biesheuvel"}]},{"@type":"WebSite","@id":"https:\/\/www.vanoorschot.nl\/en\/#website","url":"https:\/\/www.vanoorschot.nl\/en\/","name":"Uitgeverij Van Oorschot","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vanoorschot.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.vanoorschot.nl\/en\/wp-json\/wp\/v2\/oorschot_writer\/241619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vanoorschot.nl\/en\/wp-json\/wp\/v2\/oorschot_writer"}],"about":[{"href":"https:\/\/www.vanoorschot.nl\/en\/wp-json\/wp\/v2\/types\/oorschot_writer"}],"author":[{"embeddable":true,"href":"https:\/\/www.vanoorschot.nl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vanoorschot.nl\/en\/wp-json\/wp\/v2\/comments?post=241619"}],"version-history":[{"count":1,"href":"https:\/\/www.vanoorschot.nl\/en\/wp-json\/wp\/v2\/oorschot_writer\/241619\/revisions"}],"predecessor-version":[{"id":374865,"href":"https:\/\/www.vanoorschot.nl\/en\/wp-json\/wp\/v2\/oorschot_writer\/241619\/revisions\/374865"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vanoorschot.nl\/en\/wp-json\/wp\/v2\/media\/241620"}],"wp:attachment":[{"href":"https:\/\/www.vanoorschot.nl\/en\/wp-json\/wp\/v2\/media?parent=241619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}